{"id":1695,"date":"2022-08-18T22:26:55","date_gmt":"2022-08-18T20:26:55","guid":{"rendered":"http:\/\/metamandrill.com\/?p=1695"},"modified":"2023-04-04T21:53:54","modified_gmt":"2023-04-04T19:53:54","slug":"google-metaverso","status":"publish","type":"post","link":"https:\/\/metamandrill.com\/es\/google-metaverse\/","title":{"rendered":"Google Metaverso; La versi\u00f3n de Google del universo digital"},"content":{"rendered":"<p><em>Metaverso Google, el nombre solo evoca im\u00e1genes de un futuro verdaderamente expansivo. La empresa que dio forma a la Internet moderna obviamente tiene algunos planes para el futuro. Sin embargo, la compa\u00f1\u00eda puede ser un poco cautelosa con respecto a sus planes de metaverso. Pero pronto ver\u00e1 el pasado, el presente y lo que podr\u00eda suceder en el futuro del metaverso de Google.<\/em><\/p>\n<h3>Men\u00fa r\u00e1pido:<\/h3>\n<ul>\n<li><a href=\"#metaverse-as-foundation-of-google-metaverse\">El Metaverse como Foundation del Google Metaverse<\/a><\/li>\n<li><a href=\"#what-is-google\">\u00bfQu\u00e9 es Google?<\/a><\/li>\n<li><a href=\"#google-metaverse-what-we-know\">Google Metaverse: Lo que sabemos<\/a><\/li>\n<li><a href=\"#google-metaverse-past-future-products-acquisitions\">Google Metaverse Productos y adquisiciones pasados y futuros<\/a>\n<ul>\n<li><a href=\"#google-glass\">Google Glass<\/a><\/li>\n<li><a href=\"#google-daydream\">Google Daydream<\/a><\/li>\n<li><a href=\"#google-project-iris\">Google Project Iris<\/a><\/li>\n<li><a href=\"#google-project-starline\">Google Project Starline<\/a><\/li>\n<li><a href=\"#acquisition-smart-glasses-company-north\">Adquisici\u00f3n de Empresa de Gafas Inteligentes North<\/a><\/li>\n<li><a href=\"#acquisition-of-microled-startup-raxium\">Adquisici\u00f3n de MicroLED Startup Raxium<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"#google-metaverse-four-other-giant-tech-companies\">Google Metaverse y las otras cuatro gigantes tecnol\u00f3gicas<\/a>\n<ul>\n<li><a href=\"#facebook-meta-metaverse\">Facebook\/Meta&#039;s Metaverse<\/a><\/li>\n<li><a href=\"#apple-metaverse\">Apple Metaverso<\/a><\/li>\n<li><a href=\"#amazon-metaverse\">Amazon Metaverso<\/a><\/li>\n<li><a href=\"#microsoft-metaverse\">Microsoft Metaverso<\/a><a id=\"metaverse-as-foundation-of-google-metaverse\"><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2>El Metaverse como Foundation del Google Metaverse<\/h2>\n<p>El metaverso Google se deriva de la importancia de la <a href=\"http:\/\/metamandrill.com\/es\/metaverso\/\">metaverso<\/a> s\u00ed mismo. Lo mejor es ver el metaverso como un mundo completamente digital, o incluso un universo, que existe junto a la realidad f\u00edsica. La devoci\u00f3n de un arquitecto por algo puede conducir a la creaci\u00f3n de lugares \u00fanicos en el mundo f\u00edsico. Y la visi\u00f3n de una empresa de un significado de metaverso m\u00e1s profundo puede conducir a excelentes resultados digitales. Puede ingresar a esas creaciones y experimentarlas tal como lo har\u00eda con un edificio f\u00edsico porque el metaverso es un mundo 3D verdaderamente inmersivo e interactivo.<\/p>\n<p>Y de manera similar, puede invitar a amigos y familiares a unirse a usted en esa exploraci\u00f3n. La forma en que lo haga variar\u00e1 seg\u00fan lo que est\u00e9 usando para acceder al metaverso. La realidad virtual (VR) y la realidad aumentada (AR) son las opciones m\u00e1s inmersivas. Pero las computadoras, los tel\u00e9fonos e incluso las consolas de videojuegos pueden acceder a parte del metaverso. El metaverso crece continuamente, por lo que nadie sabe c\u00f3mo ser\u00e1 en el futuro. Pero sabemos que el metaverso de alguna forma es el futuro. En el art\u00edculo <a href=\"http:\/\/metamandrill.com\/es\/metaverso-significado-3\/\"><span style=\"text-decoration: underline;\">\u201cMetaverso Significado; Diferentes formas de definir el Metaverse\u201d<\/span><\/a>, puede ver c\u00f3mo los diferentes significados personales del metaverso pueden dar forma a ese medio.<a id=\"what-is-google\"><\/a><\/p>\n<h2>\u00bfQu\u00e9 es Google?<\/h2>\n<p>Cualquier implementaci\u00f3n del metaverso se basa en el esp\u00edritu subyacente de sus creadores. Entonces, para comprender el metaverso Google, debe comprender Google. La gente a menudo piensa en Google como un motor de b\u00fasqueda. Y Google Search fue, de hecho, el primer servicio significativo de Google cuando se lanz\u00f3 por primera vez en 1998. Como se conoce hoy, Google comenz\u00f3 en 2004 con el lanzamiento de Gmail. El servicio era bastante exclusivo en ese momento. Los usuarios necesitaban una invitaci\u00f3n para registrarse en el servicio. Esto permiti\u00f3 que Google escalara lentamente para satisfacer las necesidades de los usuarios. Google finalmente lleg\u00f3 a un punto en el que su infraestructura pod\u00eda funcionar de manera eficiente como una plataforma basada en la web. La empresa populariz\u00f3 r\u00e1pidamente la idea de las aplicaciones que se ejecutan en un navegador.<\/p>\n<p>Servicios como Google Maps, Google Docs, Google Drive y muchos otros demostraron que un navegador podr\u00eda actuar como una plataforma inform\u00e1tica en s\u00ed mismo. Y Google mejorar\u00eda a\u00fan m\u00e1s esta experiencia al crear el navegador Chrome utilizando un motor Javascript altamente optimizado especialmente dise\u00f1ado para aplicaciones web. El siguiente gran avance de Google se produjo en 2008 cuando particip\u00f3 en el lanzamiento del primer tel\u00e9fono con tecnolog\u00eda Android. En ese momento, Google tuvo una influencia significativa en la mayor\u00eda de las plataformas inform\u00e1ticas.<a id=\"google-metaverse-what-we-know\"><\/a><\/p>\n<h2>Google Metaverse: Lo que sabemos<\/h2>\n<p>Muchos de los detalles del pr\u00f3ximo metaverso Google todav\u00eda est\u00e1n en secreto. Pero el CEO de Google, Sundar Pichai, recientemente se sent\u00f3 a discutir el metaverso con Emily Chang de Bloomberg. Pichai puso especial \u00e9nfasis en la forma en que las personas se relacionan con las computadoras. Afirma que la inform\u00e1tica se adapta a las personas en lugar de que las personas se adapten a las computadoras. El CEO enfatiz\u00f3 que la interacci\u00f3n entre humanos y computadoras no siempre se dar\u00e1 simplemente en la forma de alguien hablando con un rect\u00e1ngulo negro frente a ellos.<\/p>\n<p>En cambio, Pichai cree que las computadoras se volver\u00e1n m\u00e1s inmersivas para que las personas puedan hablarles como lo har\u00edan con otro ser humano. Adem\u00e1s, resalt\u00f3 que las interfaces inform\u00e1ticas siempre estar\u00e1n ah\u00ed cuando la gente las necesite. Este futuro vendr\u00e1 en forma de computaci\u00f3n ambiental y AR. Ambiente, en este contexto, se refiere al entorno inmediato de uno. Y AR se refiere a la realidad aumentada que puede intercalar informaci\u00f3n digital en entornos anal\u00f3gicos. Esto significa que las personas pueden tener una plataforma inform\u00e1tica siempre activa que combina el mundo f\u00edsico y el digital. Varias implementaciones de metaverso tienden a enfatizar esta idea en un grado u otro.<\/p>\n<p>Y parece que Google, en particular, quiere difuminar la distinci\u00f3n entre el mundo f\u00edsico y el digital. Aunque Pichai tambi\u00e9n enfatiz\u00f3 el hecho de que diferentes personas a menudo quieren decir otras cosas cuando hablan sobre el metaverso. El significado del metaverso generalmente diferir\u00e1 enormemente en varios contextos cuando se discuta el tema. Chang presion\u00f3 al CEO para obtener m\u00e1s detalles sobre lo que cree que ser\u00e1 el metaverso. Como era de esperar, Pichai no dijo nada sobre los detalles de los planes del metaverso de Google, pero se\u00f1al\u00f3 que prev\u00e9 que las computadoras evolucionen de una manera inmersiva a trav\u00e9s de la realidad aumentada. Como pronto ver\u00e1, esto se alinea con muchos proyectos p\u00fablicos relacionados con el metaverso Google.<\/p>\n<h4><strong>V\u00eddeo: Presentaci\u00f3n de ARCore<\/strong><\/h4>\n<div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;\"><div class=\"video-shortcode\"><lite-youtube videoid=\"ttdPqly4OF8\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"YouTube reproductor de v\u00eddeo 1\" data-button-label=\"Play Video\" width=\"600\" height=\"360\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div>\n<h2><a id=\"google-metaverse-past-future-products-acquisitions\"><\/a>Google Metaverse Productos y adquisiciones pasados y futuros<\/h2>\n<p>Un estilo de metaverso Google puede ser dif\u00edcil de precisar porque la producci\u00f3n de la empresa puede ser muy prol\u00edfica. Google nunca ha sido t\u00edmido a la hora de experimentar. La empresa desarrolla y adquiere varias tecnolog\u00edas que a menudo experimentan cambios radicales con el tiempo. Pero los siguientes proyectos trabajados o adquiridos por Google brindan algunas pistas s\u00f3lidas sobre lo que podr\u00eda venir en el futuro.<a id=\"google-glass\"><\/a><\/p>\n<h3>Google Glass<\/h3>\n<p>Google Glass es una especie de rareza en el metaverso Google. Se anunci\u00f3 por primera vez al p\u00fablico en 2013 en medio de muchos conceptos err\u00f3neos. Mucha gente pens\u00f3 que ofrec\u00eda las funciones de realidad aumentada m\u00e1s avanzadas en los dispositivos de \u00faltima generaci\u00f3n de la actualidad. Y cuando la gente se enter\u00f3 de que Google Glass estaba m\u00e1s enfocado en grabar im\u00e1genes y videos, gener\u00f3 una preocupaci\u00f3n p\u00fablica generalizada sobre la vigilancia encubierta.<\/p>\n<p>Al final, la versi\u00f3n original de Google Glass nunca tuvo un lanzamiento generalizado completo al p\u00fablico. Pero Google Glass tuvo \u00e9xito en espacios profesionales para garantizar una segunda edici\u00f3n: Google Glass Enterprise Edition. Enterprise Edition vio un uso a\u00fan m\u00e1s variado en campos como la medicina. Y en 2019, Google anunci\u00f3 el Google Glass Enterprise Edition 2 con funciones mucho m\u00e1s avanzadas que el original. Glass no se hizo popular entre el p\u00fablico, pero sigue siendo fuerte entre los usuarios especializados de nivel empresarial.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre Google Glass Enterprise Edition 2, lea <a href=\"http:\/\/metamandrill.com\/es\/google-glasses\/\"><span style=\"text-decoration: underline;\">\u201cGoogle Glasses; M\u00e1s informaci\u00f3n sobre Google Glass Enterprise Edition 2\u201d<\/span><\/a>.<\/p>\n<h4><strong>V\u00eddeo: Glass Enterprise Edition 2<\/strong><\/h4>\n<div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;\"><div class=\"video-shortcode\"><lite-youtube videoid=\"5IK-zU51MU4\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"YouTube reproductor de v\u00eddeo 2\" data-button-label=\"Play Video\" width=\"600\" height=\"360\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div>\n<h3><a id=\"google-daydream\"><\/a>Google Daydream<\/h3>\n<p>Google Daydream fue una especie de continuaci\u00f3n de Google Cardboard. Al igual que Cardboard, Daydream funcion\u00f3 esencialmente convirtiendo su tel\u00e9fono Android en una pantalla de realidad virtual. La principal diferencia es que Daydream presentaba hardware dedicado. Daydream consta de un auricular con una bah\u00eda para sostener su tel\u00e9fono y un controlador VR.<\/p>\n<p>La tecnolog\u00eda era innovadora. Pero Google cree que el principal punto de falla provino del hecho de que las personas perdieron instant\u00e1neamente el uso de sus tel\u00e9fonos cuando usaban Daydream. Cuando alguien usa un dedicado <a href=\"http:\/\/metamandrill.com\/es\/auriculares-vr\/\">auriculares de realidad virtual<\/a>, a\u00fan pueden tomar su tel\u00e9fono para hacer una llamada o consultar una aplicaci\u00f3n. Pero Daydream requer\u00eda que las personas eligieran entre usar su tel\u00e9fono como un dispositivo de realidad virtual o usar su tel\u00e9fono como estaban acostumbrados. Adem\u00e1s de eso, el precio de $100 de Daydream no ofrec\u00eda mucho m\u00e1s de lo que se pod\u00eda obtener con Google Cardboard. Y Google Cardboard era, literalmente, algo que pod\u00edas hacer con cart\u00f3n.<\/p>\n<h4><strong>V\u00eddeo: Conoce la vista Google Daydream<\/strong><\/h4>\n<div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;\"><div class=\"video-shortcode\"><lite-youtube videoid=\"xSnkjwqdsUE\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"YouTube reproductor de v\u00eddeo 3\" data-button-label=\"Play Video\" width=\"600\" height=\"360\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div>\n<h3><a id=\"google-project-iris\"><\/a>Google Project Iris<\/h3>\n<p>El Project Iris de Google ofrece una versi\u00f3n inusual y \u00fanica de la realidad aumentada. La parte m\u00e1s desafiante de la realidad aumentada siempre ha sido la pantalla. Es dif\u00edcil representar el tipo de gr\u00e1ficos que ve en una pantalla de alta resoluci\u00f3n cuando se trabaja con algo del tama\u00f1o de un par de anteojos. Google est\u00e1 probando algo nuevo como una forma de solucionar el problema. El experimento no usa lentes. Google Project Iris renuncia al factor de forma de gafas que normalmente se ve en los sistemas AR y, en cambio, opta por un auricular estilo VR.<\/p>\n<p>Google mantiene en secreto la mayor\u00eda de los detalles relacionados con Project Iris. Solo unas 300 personas trabajan con Project Iris, escondidas detr\u00e1s de un estricto sistema de seguridad. Pero parece aprovechar las poderosas supercomputadoras de Google para realizar procesamiento gr\u00e1fico remoto. Si eso es cierto, puede ofrecer la mejor vista posible de un mundo f\u00edsico combinado con el metaverso Google m\u00e1s grande.<a id=\"google-project-starline\"><\/a><\/p>\n<h3>Google Project Starline<\/h3>\n<p>La realidad aumentada generalmente se enfoca en fusionar el metaverso y el mundo f\u00edsico. Proyectos masivos como ese a menudo vienen con obst\u00e1culos t\u00e9cnicos iguales. Pero, \u00bfy si solo necesitara trabajar con un \u00fanico punto de datos? Digamos, \u00bfrepresentar un solo individuo en lugar de un metaverso completo? Esa es la premisa de Google Project Starline. Es una versi\u00f3n muy diferente de un metaverso Google destinado simplemente a unir a dos personas.<\/p>\n<p>Google lo describe como una especie de espejo m\u00e1gico. Es una pantalla bidireccional que act\u00faa como una ventana a otro dispositivo Google Project Starline vinculado. De alguna manera, no es muy diferente a un chat de video. El principal factor diferenciador para el usuario final es el tama\u00f1o. Starline utiliza una pantalla de tama\u00f1o natural que muestra a la otra persona en su tama\u00f1o real. Pero a nivel t\u00e9cnico, Project Starline usa computaci\u00f3n avanzada para simular volumen y profundidad para hacer que las personas parezcan tridimensionales.<\/p>\n<h4><strong>V\u00eddeo: Project Starline: Si\u00e9ntete como si estuvieras ah\u00ed, juntos<\/strong><\/h4>\n<div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;\"><div class=\"video-shortcode\"><lite-youtube videoid=\"Q13CishCKXY\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"YouTube reproductor de v\u00eddeo 4\" data-button-label=\"Play Video\" width=\"600\" height=\"360\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div>\n<h3><a id=\"acquisition-smart-glasses-company-north\"><\/a>Adquisici\u00f3n de Empresa de Gafas Inteligentes North<\/h3>\n<p>Project Iris muestra un tipo diferente de realidad aumentada a la que la mayor\u00eda de la gente est\u00e1 acostumbrada. Pero eso no significa que Google haya renunciado a la idea de las gafas inteligentes. Como se se\u00f1al\u00f3 anteriormente, Google tiende a experimentar con muchas ideas al mismo tiempo. Y en este caso, eso significa trabajar en Project Iris y al mismo tiempo comprar una empresa de gafas inteligentes llamada North. North lanz\u00f3 sus lentes inteligentes, llamados Focals 1.0, en 2019.<\/p>\n<p>Utiliza un l\u00e1ser en el brazo de las gafas para transmitir im\u00e1genes a la pantalla de la lente. La compa\u00f1\u00eda hab\u00eda anunciado que la versi\u00f3n 1.0 detendr\u00eda la producci\u00f3n para concentrarse en la pr\u00f3xima iteraci\u00f3n, pero las cosas han cambiado con la adquisici\u00f3n de Google. Nadie sabe para qu\u00e9 se utilizar\u00e1 la tecnolog\u00eda de North dentro de Google o si podr\u00eda fusionarse con Glass. Pero seguramente tendr\u00e1 implicaciones emocionantes para el metaverso Google.<\/p>\n<p><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-margin-top:10px;--awb-margin-bottom:5px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-dropshadow imageframe-1 hover-type-zoomin\" style=\"border:1px solid #eaeaea;border-radius:25px;-webkit-box-shadow: 5px 5px 9px rgba(193,193,193,0.3);box-shadow: 5px 5px 9px rgba(193,193,193,0.3);\"><img decoding=\"async\" width=\"1000\" height=\"450\" alt=\"lentes del norte del metaverso de google\" title=\"lentes del norte del metaverso de google\" src=\"http:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses.jpg\" class=\"img-responsive wp-image-1699\" srcset=\"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses-200x90.jpg 200w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses-400x180.jpg 400w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses-600x270.jpg 600w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses-800x360.jpg 800w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-north-glasses.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 1000px\" \/><\/span><\/div><br \/>\n<span style=\"font-size: 10pt;\"><em>Atribuci\u00f3n de imagen: <a href=\"https:\/\/www.bynorth.com\/\" target=\"_blank\" rel=\"noopener\">by North<\/a><a id=\"acquisition-of-microled-startup-raxium\"><\/a><\/em><\/span><\/p>\n<h3>Adquisici\u00f3n de MicroLED Startup Raxium<\/h3>\n<p>Google est\u00e1 casi definido por la experimentaci\u00f3n y las adquisiciones. Y North no es de ninguna manera el \u00fanico ejemplo de esa estrategia en juego dentro de la esfera AR de Google. Google adquiri\u00f3 recientemente Raxium y la tecnolog\u00eda de micropantalla de la startup. Las pantallas microLED de Raxium aprovechan una estrategia diferente a la de la mayor\u00eda de las gafas inteligentes. En lugar de usar l\u00e1seres o sistemas hologr\u00e1ficos, el microLED usa algo m\u00e1s parecido a la pantalla de un tel\u00e9fono. La principal diferencia se reduce al tama\u00f1o. Se dice que la tecnolog\u00eda de Raxium produce resultados cinco veces m\u00e1s eficientes que los r\u00e9cords mundiales establecidos anteriormente. Los MicroLED podr\u00edan producir una versi\u00f3n muy diferente del metaverso Google.<\/p>\n<p><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-margin-top:10px;--awb-margin-bottom:5px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-dropshadow imageframe-2 hover-type-zoomin\" style=\"border:1px solid #eaeaea;border-radius:25px;-webkit-box-shadow: 5px 5px 9px rgba(193,193,193,0.3);box-shadow: 5px 5px 9px rgba(193,193,193,0.3);\"><img decoding=\"async\" width=\"1000\" height=\"450\" alt=\"Google metaverso raxium\" title=\"Google metaverso raxium\" src=\"http:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium.jpg\" class=\"img-responsive wp-image-1700\" srcset=\"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium-200x90.jpg 200w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium-400x180.jpg 400w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium-600x270.jpg 600w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium-800x360.jpg 800w, https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse-raxium.jpg 1000w\" sizes=\"(max-width: 640px) 100vw, 1000px\" \/><\/span><\/div><br \/>\n<span style=\"font-size: 10pt;\"><em>Atribuci\u00f3n de imagen: <a href=\"https:\/\/www.raxium.com\/\" target=\"_blank\" rel=\"noopener\">Raxium<\/a><a id=\"google-metaverse-four-other-giant-tech-companies\"><\/a><\/em><\/span><\/p>\n<h2>Google Metaverse y las otras cuatro gigantes tecnol\u00f3gicas<\/h2>\n<p>El metaverso Google es una perspectiva emocionante. Pero la empresa no est\u00e1 sola en su empe\u00f1o por dar forma al futuro del metaverso. Todas las compa\u00f1\u00edas tecnol\u00f3gicas m\u00e1s grandes est\u00e1n trabajando en alg\u00fan aspecto del metaverso. Pero estos siguientes <a href=\"http:\/\/metamandrill.com\/es\/metaverso-empresas\/\">empresas del metaverso<\/a> tienen historias fascinantes y notables con la plataforma.<a id=\"facebook-meta-metaverse\"><\/a><\/p>\n<h3>Facebook\/Meta&#039;s Metaverse<\/h3>\n<p>Podr\u00eda decirse que Facebook, ahora conocido como Meta, tiene el liderazgo en el desarrollo de metaversos en comparaci\u00f3n con los otros gigantes tecnol\u00f3gicos. Cuando Facebook cambi\u00f3 su nombre a Meta, marc\u00f3 un cambio en el mundo. El p\u00fablico vio que el metaverso era la nueva frontera digital y que el desarrollo iba a avanzar a un ritmo r\u00e1pido.<\/p>\n<p>Meta signific\u00f3 m\u00e1s trabajo en su l\u00ednea Oculus de auriculares VR y la plataforma de metaverso Horizon. Pero esto es solo una parte de los planes m\u00e1s extensos de Meta. Puedes descubrir esos planes en el art\u00edculo <a href=\"http:\/\/metamandrill.com\/es\/facebook-metaverso-2\/\"><span style=\"text-decoration: underline;\">\u201cFacebook Metaverso; Explicado, Ejemplos, Dispositivos, Visi\u00f3n y Cr\u00edticas\u201d<\/span><\/a>.<a id=\"apple-metaverse\"><\/a><\/p>\n<h3>Apple Metaverso<\/h3>\n<p>Apple se encuentra en una posici\u00f3n inusual dentro de la competencia por el metaverso. El metaverso Google est\u00e1 repleto de proyectos y experimentos. Pero Apple est\u00e1 trabajando en el metaverso y tambi\u00e9n es bastante cauteloso al respecto. La compa\u00f1\u00eda tiende a posponer los lanzamientos hasta que est\u00e9n pulidos y <em>&quot;solo trabajo&quot;<\/em>.<\/p>\n<p>Y hay evidencia de m\u00e1s de 20 a\u00f1os de desarrollo activo dentro de Apple. Las piezas se est\u00e1n juntando y los expertos esperan que Apple lance pronto nuevo hardware de metaverso. Puede profundizar en la investigaci\u00f3n de Apple y los pr\u00f3ximos lanzamientos en el art\u00edculo <a href=\"\/es\/apple-metaverse\/\"><span style=\"text-decoration: underline;\">\u201cApple Metaverso; C\u00f3mo Apple entra en la nueva frontera digital\u201d<\/span><\/a>.<a id=\"amazon-metaverse\"><\/a><\/p>\n<h3>Amazon Metaverso<\/h3>\n<p>Amazon es otra empresa que mantiene gran parte de su desarrollo metaverso detr\u00e1s de puertas cerradas. Por el momento, se sabe que Amazon ha contratado personas espec\u00edficamente en funci\u00f3n de su experiencia con el metaverso. Y tambi\u00e9n han lanzado algunos proyectos relacionados con el metaverso. El sistema de dise\u00f1o de sala AR de Amazon es el m\u00e1s notable para los consumidores.<\/p>\n<p>Pero el sistema educativo Cloud Quest tambi\u00e9n muestra que la empresa tiene algunos recursos de metaverso a su disposici\u00f3n. Se sabe menos sobre el metaverso Amazon que sobre el metaverso Google. Pero hay pistas. Puede desentra\u00f1ar los misterios del metaverso de Amazon en el art\u00edculo <a href=\"\/es\/amazon-metaverso\/\"><span style=\"text-decoration: underline;\">\u201cAmazon Metaverso; La visi\u00f3n de Amazon entrando en el Metaverse\u201d<\/span><\/a>.<a id=\"microsoft-metaverse\"><\/a><\/p>\n<h3>Microsoft Metaverso<\/h3>\n<p>Microsoft ha sido bastante abierto sobre sus planes para el metaverso. Curiosamente, la estrategia del gigante tecnol\u00f3gico se superpone dram\u00e1ticamente con el metaverso Google. Uno de los principales puntos de inter\u00e9s compartido proviene de la realidad aumentada. Microsoft est\u00e1 aprovechando la realidad aumentada para ayudar a las empresas a compartir su experiencia personal.<\/p>\n<p>Uno de los mayores \u00e9xitos de realidad aumentada de Microsoft es su HoloLens. Pero la reciente adquisici\u00f3n de Activision Blizzard por parte de Microsoft y la propiedad de Overwatch sugieren que la compa\u00f1\u00eda se expandir\u00e1 al metaverso m\u00e1s tradicional. Puede ponerse al d\u00eda con los planes de Microsoft en <a href=\"\/es\/microsoft-metaverse\/\"><span style=\"text-decoration: underline;\">\u201cMicrosoft Metaverso; Aprenda sobre la estrategia Metaverse de Microsoft\u201d<\/span><\/a>.<\/p>\n<p><strong>El metaverso Google es un trabajo en progreso, pero es por eso que es emocionante. Ha visto en qu\u00e9 est\u00e1n trabajando el Google y sus competidores para el futuro. Ahora depende de usted controlarlos a medida que evoluciona el metaverso.<\/strong><\/p>\n<h3>\u00bfTe gust\u00f3 este art\u00edculo sobre Google Metaverse?<\/h3>\n<p>Tambi\u00e9n te pueden interesar los siguientes art\u00edculos:<\/p>\n<ul>\n<li><a href=\"http:\/\/metamandrill.com\/es\/tesla-bot-optimus\/\">Tesla Bot Optimus; La informaci\u00f3n m\u00e1s reciente sobre el robot de Tesla<\/a><\/li>\n<li><a href=\"http:\/\/metamandrill.com\/es\/indice-de-valvulas\/\">Valve Index; M\u00e1s informaci\u00f3n sobre los potentes auriculares VR de Valve<\/a><\/li>\n<li><a href=\"http:\/\/metamandrill.com\/es\/nft-art\/\">Gu\u00eda de arte NFT; Significado, ejemplos, mercados y c\u00f3mo comprar<\/a><\/li>\n<li><a href=\"http:\/\/metamandrill.com\/es\/metaverso-trabajos\/\">Metaverso Trabajos; Aprenda todo sobre su carrera en el Metaverse<\/a><\/li>\n<\/ul>\n<div class='code-block code-block-1' style='margin: 8px 0; clear: both;'>\n<h4>M\u00e1s temas inmersivos relacionados con la tecnolog\u00eda<\/h4>\n<strong>Metamandrill.com<\/strong> proporciona informaci\u00f3n explicativa y pr\u00e1ctica sobre tecnolog\u00edas inmersivas y temas relacionados, como <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/realidad-aumentada\/\">realidad aumentada<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/realidad-virtual\/\">realidad virtual<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/mundos-virtuales\/\">juegos y mundos virtuales<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/tecnologia\/\">dispositivos y equipo<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/entrevistas\/\">Entrevistas a fundadores<\/a><\/span>, <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/eventos\/\">Informaci\u00f3n del evento<\/a><\/span>, y <span style=\"text-decoration: underline;\"><a href=\"https:\/\/metamandrill.com\/es\/categoria\/explicadores\/\">explicadores y gu\u00edas<\/a><\/span>.<\/div>","protected":false},"excerpt":{"rendered":"<p>Google metaverse, the name alone conjures up images of a truly expansive future. The company that shaped the modern Internet obviously has some plans for where it&#8217;ll go in the  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":1705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,12,1],"tags":[],"class_list":["post-1695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-augmented-reality","category-companies","category-metaverse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google Metaverse; Google&#039;s Take on the Digital Universe<\/title>\n<meta name=\"description\" content=\"Google metaverse options are examined in detail and include prior projects from Google along with in-progress developments and competition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metamandrill.com\/es\/google-metaverso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Metaverse; Google&#039;s Take on the Digital Universe\" \/>\n<meta property=\"og:description\" content=\"Google metaverse options are examined in detail and include prior projects from Google along with in-progress developments and competition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metamandrill.com\/es\/google-metaverso\/\" \/>\n<meta property=\"og:site_name\" content=\"Metamandrill.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/metamandrill\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T20:26:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T19:53:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Metamandrill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@metamandrillcom\" \/>\n<meta name=\"twitter:site\" content=\"@metamandrillcom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Metamandrill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/\"},\"author\":{\"name\":\"Metamandrill\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#\\\/schema\\\/person\\\/15fc57bf1869f680de263998690cc4a2\"},\"headline\":\"Google Metaverse; Google&#8217;s Take on the Digital Universe\",\"datePublished\":\"2022-08-18T20:26:55+00:00\",\"dateModified\":\"2023-04-04T19:53:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/\"},\"wordCount\":3151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/google-metaverse.jpg\",\"articleSection\":[\"Augmented Reality Information\",\"Companies &amp; Brands\",\"Metaverse\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/\",\"url\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/\",\"name\":\"Google Metaverse; Google's Take on the Digital Universe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/google-metaverse.jpg\",\"datePublished\":\"2022-08-18T20:26:55+00:00\",\"dateModified\":\"2023-04-04T19:53:54+00:00\",\"description\":\"Google metaverse options are examined in detail and include prior projects from Google along with in-progress developments and competition.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/google-metaverse.jpg\",\"contentUrl\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/google-metaverse.jpg\",\"width\":1200,\"height\":628,\"caption\":\"google metaverse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/de\\\/google-metaverse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metamandrill.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Metaverse; Google&#8217;s Take on the Digital Universe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/\",\"name\":\"Metamandrill.com\",\"description\":\"Metaverse information\",\"publisher\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#organization\",\"name\":\"Metamandrill.com\",\"url\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Metamandrill-logo.png\",\"contentUrl\":\"https:\\\/\\\/metamandrill.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Metamandrill-logo.png\",\"width\":250,\"height\":162,\"caption\":\"Metamandrill.com\"},\"image\":{\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/metamandrill\\\/\",\"https:\\\/\\\/x.com\\\/metamandrillcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metamandrill.com\\\/es\\\/#\\\/schema\\\/person\\\/15fc57bf1869f680de263998690cc4a2\",\"name\":\"Metamandrill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g\",\"caption\":\"Metamandrill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google Metaverso; La versi\u00f3n de Google del universo digital","description":"Las opciones del metaverso Google se examinan en detalle e incluyen proyectos anteriores de Google junto con desarrollos en curso y competencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metamandrill.com\/es\/google-metaverso\/","og_locale":"es_ES","og_type":"article","og_title":"Google Metaverse; Google's Take on the Digital Universe","og_description":"Google metaverse options are examined in detail and include prior projects from Google along with in-progress developments and competition.","og_url":"https:\/\/metamandrill.com\/es\/google-metaverso\/","og_site_name":"Metamandrill.com","article_publisher":"https:\/\/www.facebook.com\/metamandrill\/","article_published_time":"2022-08-18T20:26:55+00:00","article_modified_time":"2023-04-04T19:53:54+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg","type":"image\/jpeg"}],"author":"Metamandrill","twitter_card":"summary_large_image","twitter_creator":"@metamandrillcom","twitter_site":"@metamandrillcom","twitter_misc":{"Escrito por":"Metamandrill","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#article","isPartOf":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/"},"author":{"name":"Metamandrill","@id":"https:\/\/metamandrill.com\/es\/#\/schema\/person\/15fc57bf1869f680de263998690cc4a2"},"headline":"Google Metaverse; Google&#8217;s Take on the Digital Universe","datePublished":"2022-08-18T20:26:55+00:00","dateModified":"2023-04-04T19:53:54+00:00","mainEntityOfPage":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/"},"wordCount":3151,"commentCount":0,"publisher":{"@id":"https:\/\/metamandrill.com\/es\/#organization"},"image":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#primaryimage"},"thumbnailUrl":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg","articleSection":["Augmented Reality Information","Companies &amp; Brands","Metaverse"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/metamandrill.com\/de\/google-metaverse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/","url":"https:\/\/metamandrill.com\/de\/google-metaverse\/","name":"Google Metaverso; La versi\u00f3n de Google del universo digital","isPartOf":{"@id":"https:\/\/metamandrill.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#primaryimage"},"image":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#primaryimage"},"thumbnailUrl":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg","datePublished":"2022-08-18T20:26:55+00:00","dateModified":"2023-04-04T19:53:54+00:00","description":"Las opciones del metaverso Google se examinan en detalle e incluyen proyectos anteriores de Google junto con desarrollos en curso y competencia.","breadcrumb":{"@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metamandrill.com\/de\/google-metaverse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#primaryimage","url":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg","contentUrl":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/08\/google-metaverse.jpg","width":1200,"height":628,"caption":"google metaverse"},{"@type":"BreadcrumbList","@id":"https:\/\/metamandrill.com\/de\/google-metaverse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metamandrill.com\/"},{"@type":"ListItem","position":2,"name":"Google Metaverse; Google&#8217;s Take on the Digital Universe"}]},{"@type":"WebSite","@id":"https:\/\/metamandrill.com\/es\/#website","url":"https:\/\/metamandrill.com\/es\/","name":"Metamandrill.com","description":"Metainformaci\u00f3n inversa","publisher":{"@id":"https:\/\/metamandrill.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metamandrill.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/metamandrill.com\/es\/#organization","name":"Metamandrill.com","url":"https:\/\/metamandrill.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metamandrill.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/01\/Metamandrill-logo.png","contentUrl":"https:\/\/metamandrill.com\/wp-content\/uploads\/2022\/01\/Metamandrill-logo.png","width":250,"height":162,"caption":"Metamandrill.com"},"image":{"@id":"https:\/\/metamandrill.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/metamandrill\/","https:\/\/x.com\/metamandrillcom"]},{"@type":"Person","@id":"https:\/\/metamandrill.com\/es\/#\/schema\/person\/15fc57bf1869f680de263998690cc4a2","name":"Metamandrill","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50263c6b02ae4a5d0e48572c0af84f240382c6c619ae06d732c79fc61bee49c2?s=96&d=identicon&r=g","caption":"Metamandrill"}}]}},"_links":{"self":[{"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/posts\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/comments?post=1695"}],"version-history":[{"count":12,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/posts\/1695\/revisions"}],"predecessor-version":[{"id":2300,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/posts\/1695\/revisions\/2300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/media\/1705"}],"wp:attachment":[{"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/categories?post=1695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metamandrill.com\/es\/wp-json\/wp\/v2\/tags?post=1695"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}